{"id":11578,"date":"2026-05-11T05:02:00","date_gmt":"2026-05-11T04:02:00","guid":{"rendered":"https:\/\/pueblosycomarcas.com\/?p=11578"},"modified":"2026-05-10T16:52:25","modified_gmt":"2026-05-10T15:52:25","slug":"club-deportivo-la-victoria-campeon-de-espana-en-la-copa-nacional-conjuntos-base-de-gimnasia-ritmica","status":"publish","type":"post","link":"https:\/\/pueblosycomarcas.com\/en\/club-deportivo-la-victoria-campeon-de-espana-en-la-copa-nacional-conjuntos-base-de-gimnasia-ritmica\/","title":{"rendered":"Club Deportivo La Victoria campe\u00f3n de Espa\u00f1a en la Copa Nacional Conjuntos Base de Gimnasia R\u00edtmica"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"11578\" class=\"elementor elementor-11578\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b551b06 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"3b551b06\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6dd7285e elementor-widget elementor-widget-image\" data-id=\"6dd7285e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.termicasalfonso.es\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"220\" src=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-instalaciones-alfonso.jpg\" class=\"attachment-large size-large wp-image-107\" alt=\"\" srcset=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-instalaciones-alfonso.jpg 400w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-instalaciones-alfonso-300x165.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3aa411e4 elementor-widget elementor-widget-text-editor\" data-id=\"3aa411e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><h6><strong><em>Deportes y ocio<\/em><\/strong><\/h6><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-454b768c elementor-widget elementor-widget-heading\" data-id=\"454b768c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Club Deportivo La Victoria campe\u00f3n de Espa\u00f1a en la Copa Nacional Conjuntos Base de Gimnasia R\u00edtmica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6045e295 elementor-widget elementor-widget-text-editor\" data-id=\"6045e295\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><h6><em><strong>En esta ocasi\u00f3n las sonrientes integrantes del equipo alev\u00edn del club La Victoria, Vega Baquer\u00edn, Vega del Arco, Mar\u00eda Lara, Nahia L\u00e1zaro y Sara Gonz\u00e1lez se ba\u00f1aron de un oro que sabe a gloria al proclamarse Campeonas de Espa\u00f1a<\/strong><\/em><\/h6><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54439862 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"54439862\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4811d918 elementor-widget elementor-widget-image\" data-id=\"4811d918\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260511_cd_victoria.jpg\" class=\"attachment-large size-large wp-image-11579\" alt=\"\" srcset=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260511_cd_victoria.jpg 800w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260511_cd_victoria-300x150.jpg 300w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260511_cd_victoria-768x384.jpg 768w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260511_cd_victoria-18x9.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-845e33e elementor-widget elementor-widget-text-editor\" data-id=\"845e33e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.facebook.com\/Pueblos-y-Comarcas-125437870924169\/?fref=ts\"><strong><em>Pueblosycomarcas.com<\/em><\/strong><\/a><strong><em>;\u00a0<\/em><\/strong><a href=\"https:\/\/twitter.com\/PueblosComarcas\"><strong><em>@PueblosComarcas<\/em><\/strong><\/a><\/p><p>El Club Deportivo La Victoria asalta el Palacio de los Deportes de Santander, gracias a otra nueva medalla de oro alcanzada en la Copa Nacional Conjuntos Base de Gimnasia R\u00edtmica; y es que los logros nacionales que amontona el club vallisoletano no tienen parang\u00f3n, situando a la ciudad de Valladolid asiduamente en lo m\u00e1s alto del p\u00f3dium de la gimnasia nacional.<\/p><p>En esta ocasi\u00f3n las sonrientes integrantes del equipo alev\u00edn del club La Victoria, Vega Baquer\u00edn, Vega del Arco, Mar\u00eda Lara, Nahia L\u00e1zaro y Sara Gonz\u00e1lez se ba\u00f1aron de un oro que sabe a gloria al proclamarse Campeonas de Espa\u00f1a en la copa nacional conjuntos base con un ejercicio de lo m\u00e1s art\u00edstico y con una puesta en escena basada en la pel\u00edcula de the polar express, que les supuso un total de 16,450 puntos, por delante del club Oleza de la comunidad Valenciana y Elegua de Canarias.<\/p><p>Con una trayectoria deportiva inmaculada, en esta ocasi\u00f3n han accedido al para\u00edso de la gimnasia con su cuarto oro nacional gracias a la mejor nota de ejecuci\u00f3n de la competici\u00f3n y a una excelente composici\u00f3n art\u00edstica, sin olvidar el a\u00f1o pasado en Granada con un ejercicio de lo m\u00e1s art\u00edstico y con una puesta en escena basada en la pel\u00edcula de Bitelch\u00fas, el anterior en el mismo escenario de Santander y hace dos proclam\u00e1ndose campeonas de Espa\u00f1a en Pamplona.<\/p><p>En un palacio de los deportes donde la tensi\u00f3n y los nervios estaban a flor de piel desde las nueve de la ma\u00f1ana, que fue cuando las gimnastas de la Victoria saltaban al tapiz en segunda posici\u00f3n, r\u00e1pidamente encabezaron la tabla clasificatoria teniendo que esperar a ver como completaban su participaci\u00f3n los cincuenta clubes aspirantes a conseguir el metal m\u00e1s preciado, y fueron pasadas las 13.30h cuando el club La Victoria sabore\u00f3 otro nuevo \u00e9xito deportivo que no hace que confirmar nuevamente el buen hacer del equipo t\u00e9cnico, siendo un claro reflejo de un proyecto deportivo de \u00e9xito que le ha proporcionado m\u00e1s de cuarenta medallas nacionales a lo largo de los \u00faltimos a\u00f1os.<\/p><p>Santander acoge desde el jueves a 2500 gimnastas y justamente en la jornada inicial es donde los nuevos equipos del club la victoria en las categor\u00edas prebenjamin y benjam\u00edn se estrenaron en su primera cita nacional, situ\u00e1ndose a la postre en la cuarta y novena posici\u00f3n respectivamente; y es que las m\u00e1s peque\u00f1as del club rozaron el podio a tan solo cincuenta cent\u00e9simas del equipo madrile\u00f1o Hoyos del Manzanares, lo que presagia un futuro prometedor para el club vallisoletano.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3070780e e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"3070780e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61bcb671 elementor-widget elementor-widget-image\" data-id=\"61bcb671\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.granjapinilla.com\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"639\" height=\"150\" src=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-granja-pinilla.jpg\" class=\"attachment-large size-large wp-image-105\" alt=\"\" srcset=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-granja-pinilla.jpg 639w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-granja-pinilla-300x70.jpg 300w\" sizes=\"(max-width: 639px) 100vw, 639px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Deportes y ocio Club Deportivo La Victoria campe\u00f3n de Espa\u00f1a en la Copa Nacional Conjuntos Base de Gimnasia R\u00edtmica En esta ocasi\u00f3n las sonrientes integrantes del equipo alev\u00edn del club La Victoria, Vega Baquer\u00edn, Vega del Arco, Mar\u00eda Lara, Nahia L\u00e1zaro y Sara Gonz\u00e1lez se ba\u00f1aron de un oro que sabe a gloria al proclamarse Campeonas de Espa\u00f1a Pueblosycomarcas.com;\u00a0@PueblosComarcas El Club Deportivo La Victoria asalta el Palacio de los Deportes de Santander, gracias a otra nueva medalla de oro alcanzada en la Copa Nacional Conjuntos Base de Gimnasia R\u00edtmica; y es que los logros nacionales que amontona el club vallisoletano no tienen parang\u00f3n, situando a la ciudad de Valladolid asiduamente en lo m\u00e1s alto del p\u00f3dium de la gimnasia nacional. En esta ocasi\u00f3n las sonrientes integrantes del equipo alev\u00edn del club La Victoria, Vega Baquer\u00edn, Vega del Arco, Mar\u00eda Lara, Nahia L\u00e1zaro y Sara Gonz\u00e1lez se ba\u00f1aron de un oro que sabe a gloria al proclamarse Campeonas de Espa\u00f1a en la copa nacional conjuntos base con un ejercicio de lo m\u00e1s art\u00edstico y con una puesta en escena basada en la pel\u00edcula de the polar express, que les supuso un total de 16,450 puntos, por delante del club Oleza de la comunidad Valenciana y Elegua de Canarias. Con una trayectoria deportiva inmaculada, en esta ocasi\u00f3n han accedido al para\u00edso de la gimnasia con su cuarto oro nacional gracias a la mejor nota de ejecuci\u00f3n de la competici\u00f3n y a una excelente composici\u00f3n art\u00edstica, sin olvidar el a\u00f1o pasado en Granada con un ejercicio de lo m\u00e1s art\u00edstico y con una puesta en escena basada en la pel\u00edcula de Bitelch\u00fas, el anterior en el mismo escenario de Santander y hace dos proclam\u00e1ndose campeonas de Espa\u00f1a en Pamplona. En un palacio de los deportes donde la tensi\u00f3n y los nervios estaban a flor de piel desde las nueve de la ma\u00f1ana, que fue cuando las gimnastas de la Victoria saltaban al tapiz en segunda posici\u00f3n, r\u00e1pidamente encabezaron la tabla clasificatoria teniendo que esperar a ver como completaban su participaci\u00f3n los cincuenta clubes aspirantes a conseguir el metal m\u00e1s preciado, y fueron pasadas las 13.30h cuando el club La Victoria sabore\u00f3 otro nuevo \u00e9xito deportivo que no hace que confirmar nuevamente el buen hacer del equipo t\u00e9cnico, siendo un claro reflejo de un proyecto deportivo de \u00e9xito que le ha proporcionado m\u00e1s de cuarenta medallas nacionales a lo largo de los \u00faltimos a\u00f1os. Santander acoge desde el jueves a 2500 gimnastas y justamente en la jornada inicial es donde los nuevos equipos del club la victoria en las categor\u00edas prebenjamin y benjam\u00edn se estrenaron en su primera cita nacional, situ\u00e1ndose a la postre en la cuarta y novena posici\u00f3n respectivamente; y es que las m\u00e1s peque\u00f1as del club rozaron el podio a tan solo cincuenta cent\u00e9simas del equipo madrile\u00f1o Hoyos del Manzanares, lo que presagia un futuro prometedor para el club vallisoletano.<\/p>","protected":false},"author":2,"featured_media":11579,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ngg_post_thumbnail":0,"footnotes":""},"categories":[11,16],"tags":[66,22],"class_list":["post-11578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes-y-ocio","category-portada","tag-cd-la-victoria","tag-valladolid"],"aioseo_notices":[],"rttpg_featured_image_url":{"full":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260511_cd_victoria.jpg",800,400,false],"landscape":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260511_cd_victoria.jpg",800,400,false],"portraits":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260511_cd_victoria.jpg",800,400,false],"thumbnail":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260511_cd_victoria-150x150.jpg",150,150,true],"medium":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260511_cd_victoria-300x150.jpg",300,150,true],"large":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260511_cd_victoria.jpg",800,400,false],"1536x1536":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260511_cd_victoria.jpg",800,400,false],"2048x2048":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260511_cd_victoria.jpg",800,400,false],"trp-custom-language-flag":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260511_cd_victoria-18x9.jpg",18,9,true]},"rttpg_author":{"display_name":"Juanjo","author_link":"https:\/\/pueblosycomarcas.com\/en\/author\/pueblosycomarcas\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/pueblosycomarcas.com\/en\/category\/deportes-y-ocio\/\" rel=\"category tag\">Deporte y Ocio<\/a> <a href=\"https:\/\/pueblosycomarcas.com\/en\/category\/portada\/\" rel=\"category tag\">Portada<\/a>","rttpg_excerpt":"Deportes y ocio Club Deportivo La Victoria campe\u00f3n de Espa\u00f1a en la Copa Nacional Conjuntos Base de Gimnasia R\u00edtmica En esta ocasi\u00f3n las sonrientes integrantes del equipo alev\u00edn del club La Victoria, Vega Baquer\u00edn, Vega del Arco, Mar\u00eda Lara, Nahia L\u00e1zaro y Sara Gonz\u00e1lez se ba\u00f1aron de un oro que sabe a gloria al proclamarse&hellip;","_links":{"self":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts\/11578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/comments?post=11578"}],"version-history":[{"count":5,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts\/11578\/revisions"}],"predecessor-version":[{"id":11584,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts\/11578\/revisions\/11584"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/media\/11579"}],"wp:attachment":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/media?parent=11578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/categories?post=11578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/tags?post=11578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}