{"id":11504,"date":"2026-05-08T16:54:23","date_gmt":"2026-05-08T15:54:23","guid":{"rendered":"https:\/\/pueblosycomarcas.com\/?p=11504"},"modified":"2026-05-08T16:56:18","modified_gmt":"2026-05-08T15:56:18","slug":"la-archidiocesis-de-valladolid-homenajeara-el-lunes-a-ocho-presbiteros-que-celebran-este-2026-sus-70-60-50-y-25-anos-de-vida-sacerdotal","status":"publish","type":"post","link":"https:\/\/pueblosycomarcas.com\/en\/la-archidiocesis-de-valladolid-homenajeara-el-lunes-a-ocho-presbiteros-que-celebran-este-2026-sus-70-60-50-y-25-anos-de-vida-sacerdotal\/","title":{"rendered":"La Archidi\u00f3cesis de Valladolid homenajear\u00e1 el lunes a ocho presb\u00edteros que celebran este 2026 sus 70, 60, 50 y 25 a\u00f1os de vida sacerdotal"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"11504\" class=\"elementor elementor-11504\">\n\t\t\t\t<div class=\"elementor-element elementor-element-244abf88 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"244abf88\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ae2c163 elementor-widget elementor-widget-image\" data-id=\"3ae2c163\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.termicasalfonso.es\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"220\" src=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-instalaciones-alfonso.jpg\" class=\"attachment-large size-large wp-image-107\" alt=\"\" srcset=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-instalaciones-alfonso.jpg 400w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-instalaciones-alfonso-300x165.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f25c3b elementor-widget elementor-widget-text-editor\" data-id=\"2f25c3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><h6><strong><em>Magazine<\/em><\/strong><\/h6><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f28a739 elementor-widget elementor-widget-heading\" data-id=\"7f28a739\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La Archidi\u00f3cesis de Valladolid homenajear\u00e1 el lunes a ocho presb\u00edteros que celebran este 2026 sus 70, 60, 50 y 25 a\u00f1os de vida sacerdotal<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e404d2 elementor-widget elementor-widget-text-editor\" data-id=\"e404d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><h6><em><strong>Coincidiendo con la festividad de San Juan de \u00c1vila, patr\u00f3n del clero secular espa\u00f1ol<\/strong><\/em><\/h6><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-152edfd3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"152edfd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40440f53 elementor-widget elementor-widget-image\" data-id=\"40440f53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260508_sacerdotes_diocesis_valladolid.jpeg\" class=\"attachment-large size-large wp-image-11505\" alt=\"\" srcset=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260508_sacerdotes_diocesis_valladolid.jpeg 800w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260508_sacerdotes_diocesis_valladolid-300x150.jpeg 300w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260508_sacerdotes_diocesis_valladolid-768x384.jpeg 768w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260508_sacerdotes_diocesis_valladolid-18x9.jpeg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Foto Archidi\u00f3cesis de Valladolid. <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21aa4dca elementor-widget elementor-widget-text-editor\" data-id=\"21aa4dca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.facebook.com\/Pueblos-y-Comarcas-125437870924169\/?fref=ts\"><em><strong>Pueblosycomarcas.com<\/strong><\/em><\/a><em><strong>;&nbsp;<\/strong><\/em><a href=\"https:\/\/twitter.com\/PueblosComarcas\"><em><strong>@PueblosComarcas<\/strong><\/em><\/a><\/p>\n<p>La Archidi\u00f3cesis de Valladolid homenajear\u00e1 el lunes 11 de mayo a ocho sacerdotes que este 2026, A\u00f1o Jubilar de la Santidad, celebran sus bodas de titanio, diamante, oro y plata sacerdotales. Es decir, el 70, 60, 50 y 25 aniversario, respectivamente, de su ordenaci\u00f3n presbiteral.<\/p>\n<p>La Delegaci\u00f3n del Clero ha decidido trasladar al lunes este acto que se enmarca en la festividad de San Juan de \u00c1vila, patr\u00f3n del clero secular espa\u00f1ol, y que la Iglesia Cat\u00f3lica celebra cada 10 de mayo. Al coincidir en domingo y para no desatender la adecuada atenci\u00f3n pastoral a los fieles vallisoletanos, la Delegaci\u00f3n ha decidido trasladar este homenaje al lunes 11 de mayo, lo que facilitar\u00e1 que alrededor de un centenar de sacerdotes, religiosos y di\u00e1conos se re\u00fanan en esta jornada festiva, de acci\u00f3n de gracias y encuentro para homenajear a sus hermanos en el presbiterio.<\/p>\n<p>Entre los homenajeados se encuentra Daniel P\u00e9rez que, a sus 70 a\u00f1os de vida sacerdotal, sigue prestando su colaboraci\u00f3n en la Residencia Santa Marta.<\/p>\n<p>Cumplen su 60 aniversario como presb\u00edteros Mateo Marcos, notario mayor del Arzobispado y can\u00f3nigo de la Catedral de Valladolid; Francisco Javier Guridi (OFM), p\u00e1rroco de la Inmaculada Concepci\u00f3n de Mar\u00eda; Santiago Mil\u00e1n, misionero en Brasil; y Jes\u00fas Villace, colaborador en la Real Iglesia Parroquial de San Miguel y San Juli\u00e1n pese a estar ya jubilado.<\/p>\n<p>Por su parte, Santiago D\u00edez, tambi\u00e9n jubilado, celebra sus bodas de oro sacerdotales. Por \u00faltimo, Francisco Javier Vidal, p\u00e1rroco de La Seca, Serrada, Valdestillas y Villanueva de Duero, y Juan Jos\u00e9 Calvo, p\u00e1rroco <em>in solidum<\/em> en Pe\u00f1afiel y otras 14 localidades pertenecientes al Arciprestazgo del Duero, celebran este 2026 el 25 aniversario de su ordenaci\u00f3n sacerdotal.<\/p>\n<h4><strong>EN EL SEMINARIO DIOCESANO<\/strong><\/h4>\n<p>Las celebraciones por San Juan de \u00c1vila en Valladolid regresan este 2026 al Seminario Diocesano, tras haberse acometido la reforma de su sal\u00f3n de actos.<\/p>\n<p>La jornada comenzar\u00e1 con el rezo de la Hora Intermedia y una mesa redonda en la que cuatro generaciones de presb\u00edteros y un seminarista compartir\u00e1n \u201clos sue\u00f1os y las visiones que los movieron y que los mueven desde los inicios de su vocaci\u00f3n y de su ministerio\u201d. Con esta propuesta, que nace de la Bula de Convocaci\u00f3n del Jubileo 2025 que firm\u00f3 el fallecido Papa Francisco, la Delegaci\u00f3n del Clero de la Archidi\u00f3cesis vallisoletana ha querido poner el acento en la \u201cesperanza\u201d y en la \u201cnecesaria escucha amorosa\u201d entre j\u00f3venes y mayores \u201cpara construir juntos el futuro\u201d.<\/p>\n<p>Seguidamente, se homenajear\u00e1 a los sacerdotes que celebran el 70, 60, 50 y 25 aniversario de ordenaci\u00f3n. A la una del mediod\u00eda se celebrar\u00e1 en la capilla del Seminario la Eucarist\u00eda, que presidir\u00e1 el Arzobispo de Valladolid y presidente de la Conferencia Episcopal Espa\u00f1ola (CEE), monse\u00f1or Luis Arg\u00fcello. Y, para finalizar, los asistentes compartir\u00e1n una comida fraternal.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d0b0661 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"d0b0661\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4524746 elementor-widget elementor-widget-image\" data-id=\"4524746\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.granjapinilla.com\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"639\" height=\"150\" src=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-granja-pinilla.jpg\" class=\"attachment-large size-large wp-image-105\" alt=\"\" srcset=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-granja-pinilla.jpg 639w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-granja-pinilla-300x70.jpg 300w\" sizes=\"(max-width: 639px) 100vw, 639px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Magazine La Archidi\u00f3cesis de Valladolid homenajear\u00e1 el lunes a ocho presb\u00edteros que celebran este 2026 sus 70, 60, 50 y 25 a\u00f1os de vida sacerdotal Coincidiendo con la festividad de San Juan de \u00c1vila, patr\u00f3n del clero secular espa\u00f1ol Foto Archidi\u00f3cesis de Valladolid. Pueblosycomarcas.com;&nbsp;@PueblosComarcas La Archidi\u00f3cesis de Valladolid homenajear\u00e1 el lunes 11 de mayo a ocho sacerdotes que este 2026, A\u00f1o Jubilar de la Santidad, celebran sus bodas de titanio, diamante, oro y plata sacerdotales. Es decir, el 70, 60, 50 y 25 aniversario, respectivamente, de su ordenaci\u00f3n presbiteral. La Delegaci\u00f3n del Clero ha decidido trasladar al lunes este acto que se enmarca en la festividad de San Juan de \u00c1vila, patr\u00f3n del clero secular espa\u00f1ol, y que la Iglesia Cat\u00f3lica celebra cada 10 de mayo. Al coincidir en domingo y para no desatender la adecuada atenci\u00f3n pastoral a los fieles vallisoletanos, la Delegaci\u00f3n ha decidido trasladar este homenaje al lunes 11 de mayo, lo que facilitar\u00e1 que alrededor de un centenar de sacerdotes, religiosos y di\u00e1conos se re\u00fanan en esta jornada festiva, de acci\u00f3n de gracias y encuentro para homenajear a sus hermanos en el presbiterio. Entre los homenajeados se encuentra Daniel P\u00e9rez que, a sus 70 a\u00f1os de vida sacerdotal, sigue prestando su colaboraci\u00f3n en la Residencia Santa Marta. Cumplen su 60 aniversario como presb\u00edteros Mateo Marcos, notario mayor del Arzobispado y can\u00f3nigo de la Catedral de Valladolid; Francisco Javier Guridi (OFM), p\u00e1rroco de la Inmaculada Concepci\u00f3n de Mar\u00eda; Santiago Mil\u00e1n, misionero en Brasil; y Jes\u00fas Villace, colaborador en la Real Iglesia Parroquial de San Miguel y San Juli\u00e1n pese a estar ya jubilado. Por su parte, Santiago D\u00edez, tambi\u00e9n jubilado, celebra sus bodas de oro sacerdotales. Por \u00faltimo, Francisco Javier Vidal, p\u00e1rroco de La Seca, Serrada, Valdestillas y Villanueva de Duero, y Juan Jos\u00e9 Calvo, p\u00e1rroco in solidum en Pe\u00f1afiel y otras 14 localidades pertenecientes al Arciprestazgo del Duero, celebran este 2026 el 25 aniversario de su ordenaci\u00f3n sacerdotal. EN EL SEMINARIO DIOCESANO Las celebraciones por San Juan de \u00c1vila en Valladolid regresan este 2026 al Seminario Diocesano, tras haberse acometido la reforma de su sal\u00f3n de actos. La jornada comenzar\u00e1 con el rezo de la Hora Intermedia y una mesa redonda en la que cuatro generaciones de presb\u00edteros y un seminarista compartir\u00e1n \u201clos sue\u00f1os y las visiones que los movieron y que los mueven desde los inicios de su vocaci\u00f3n y de su ministerio\u201d. Con esta propuesta, que nace de la Bula de Convocaci\u00f3n del Jubileo 2025 que firm\u00f3 el fallecido Papa Francisco, la Delegaci\u00f3n del Clero de la Archidi\u00f3cesis vallisoletana ha querido poner el acento en la \u201cesperanza\u201d y en la \u201cnecesaria escucha amorosa\u201d entre j\u00f3venes y mayores \u201cpara construir juntos el futuro\u201d. Seguidamente, se homenajear\u00e1 a los sacerdotes que celebran el 70, 60, 50 y 25 aniversario de ordenaci\u00f3n. A la una del mediod\u00eda se celebrar\u00e1 en la capilla del Seminario la Eucarist\u00eda, que presidir\u00e1 el Arzobispo de Valladolid y presidente de la Conferencia Episcopal Espa\u00f1ola (CEE), monse\u00f1or Luis Arg\u00fcello. Y, para finalizar, los asistentes compartir\u00e1n una comida fraternal.<\/p>","protected":false},"author":2,"featured_media":11505,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,16],"tags":[52],"class_list":["post-11504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","category-portada","tag-archidiocesis-de-valladolid"],"aioseo_notices":[],"rttpg_featured_image_url":{"full":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260508_sacerdotes_diocesis_valladolid.jpeg",800,400,false],"landscape":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260508_sacerdotes_diocesis_valladolid.jpeg",800,400,false],"portraits":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260508_sacerdotes_diocesis_valladolid.jpeg",800,400,false],"thumbnail":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260508_sacerdotes_diocesis_valladolid-150x150.jpeg",150,150,true],"medium":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260508_sacerdotes_diocesis_valladolid-300x150.jpeg",300,150,true],"large":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260508_sacerdotes_diocesis_valladolid.jpeg",800,400,false],"1536x1536":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260508_sacerdotes_diocesis_valladolid.jpeg",800,400,false],"2048x2048":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260508_sacerdotes_diocesis_valladolid.jpeg",800,400,false],"trp-custom-language-flag":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260508_sacerdotes_diocesis_valladolid-18x9.jpeg",18,9,true]},"rttpg_author":{"display_name":"Juanjo","author_link":"https:\/\/pueblosycomarcas.com\/en\/author\/pueblosycomarcas\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/pueblosycomarcas.com\/en\/category\/magazine\/\" rel=\"category tag\">Magazine<\/a> <a href=\"https:\/\/pueblosycomarcas.com\/en\/category\/portada\/\" rel=\"category tag\">Portada<\/a>","rttpg_excerpt":"Magazine La Archidi\u00f3cesis de Valladolid homenajear\u00e1 el lunes a ocho presb\u00edteros que celebran este 2026 sus 70, 60, 50 y 25 a\u00f1os de vida sacerdotal Coincidiendo con la festividad de San Juan de \u00c1vila, patr\u00f3n del clero secular espa\u00f1ol Foto Archidi\u00f3cesis de Valladolid. Pueblosycomarcas.com;&nbsp;@PueblosComarcas La Archidi\u00f3cesis de Valladolid homenajear\u00e1 el lunes 11 de mayo a&hellip;","_links":{"self":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts\/11504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/comments?post=11504"}],"version-history":[{"count":8,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts\/11504\/revisions"}],"predecessor-version":[{"id":11513,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts\/11504\/revisions\/11513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/media\/11505"}],"wp:attachment":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/media?parent=11504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/categories?post=11504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/tags?post=11504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}