{"id":11332,"date":"2026-05-06T12:28:11","date_gmt":"2026-05-06T11:28:11","guid":{"rendered":"https:\/\/pueblosycomarcas.com\/?p=11332"},"modified":"2026-05-06T12:31:33","modified_gmt":"2026-05-06T11:31:33","slug":"musica-a-la-luz-de-la-virgen-de-compasco-para-comenzar-con-el-programa-del-privilegio-de-villazgo-de-aldeamayor","status":"publish","type":"post","link":"https:\/\/pueblosycomarcas.com\/en\/musica-a-la-luz-de-la-virgen-de-compasco-para-comenzar-con-el-programa-del-privilegio-de-villazgo-de-aldeamayor\/","title":{"rendered":"M\u00fasica a la luz de la Virgen de Compasco para comenzar con el programa del Privilegio de Villazgo de Aldeamayor"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"11332\" class=\"elementor elementor-11332\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2980f547 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"2980f547\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58362dab elementor-widget elementor-widget-image\" data-id=\"58362dab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.termicasalfonso.es\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"220\" src=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-instalaciones-alfonso.jpg\" class=\"attachment-large size-large wp-image-107\" alt=\"\" srcset=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-instalaciones-alfonso.jpg 400w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-instalaciones-alfonso-300x165.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-145075da elementor-widget elementor-widget-text-editor\" data-id=\"145075da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><h6><strong><em>Cultura y tradici\u00f3n<\/em><\/strong><\/h6><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7eb74067 elementor-widget elementor-widget-heading\" data-id=\"7eb74067\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u00fasica a la luz de la Virgen de Compasco para comenzar con el programa del Privilegio de Villazgo de Aldeamayor<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c890228 elementor-widget elementor-widget-text-editor\" data-id=\"5c890228\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><h6><em><strong>S\u00e9ptima edici\u00f3n del concierto de m\u00fasica cl\u00e1sica promovido por la Asociaci\u00f3n Villa de Aldeamayor organizado conjuntamente con el Ayuntamiento<\/strong><\/em><\/h6><\/li><li><h6><em><strong>Se celebrar\u00e1 el martes, 12 de mayo, a las 21:00 horas en la iglesia parroquial con la partici\u00f3n de la Camerata Europa y el tenor David Galicia Ruiz<\/strong><\/em><\/h6><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ab6704c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6ab6704c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13e30c6b elementor-widget elementor-widget-image\" data-id=\"13e30c6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_musica_luz_viegen_compasco_aldeamayor.jpeg\" class=\"attachment-large size-large wp-image-11333\" alt=\"\" srcset=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_musica_luz_viegen_compasco_aldeamayor.jpeg 800w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_musica_luz_viegen_compasco_aldeamayor-300x150.jpeg 300w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_musica_luz_viegen_compasco_aldeamayor-768x384.jpeg 768w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_musica_luz_viegen_compasco_aldeamayor-18x9.jpeg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c9dadf7 elementor-widget elementor-widget-text-editor\" data-id=\"2c9dadf7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.facebook.com\/Pueblos-y-Comarcas-125437870924169\/?fref=ts\"><strong><em>Pueblosycomarcas.com<\/em><\/strong><\/a><strong><em>;&nbsp;<\/em><\/strong><a href=\"https:\/\/twitter.com\/PueblosComarcas\"><strong><em>@PueblosComarcas<\/em><\/strong><\/a><\/p>\n<p>El pr\u00f3ximo martes, 12 de mayo, Aldeamayor de San Mart\u00edn dar\u00e1 el pistoletazo de salida al programa de actividades de su Privilegio de Villazgo 2026, celebraci\u00f3n con la que la localidad recuerda la obtenci\u00f3n de su independencia respecto a Portillo el 19 de mayo de 1776.<\/p>\n<p>Lo har\u00e1 con una cita que a\u00fana m\u00fasica, tradici\u00f3n y devoci\u00f3n como es la s\u00e9ptima edici\u00f3n de \u2018M\u00fasica a la luz de la Virgen de Compasco\u2019 que el Ayuntamiento de la localidad coorganiza con la Asociaci\u00f3n Cultural Villa de Aldamayor, promotora de la iniciativa, y con la inestimable colaboraci\u00f3n de la Cofrad\u00eda de Nuestra Se\u00f1ora de Compasco y de la Parroquia de San Mart\u00edn de Tours.<\/p>\n<p>Este concierto ha sido presentado en la ma\u00f1ana de hoy por el vicepresidente de la Diputaci\u00f3n de Valladolid, V\u00edctor Alonso, que ha estado acompa\u00f1ado por el alcalde de Aldeamayor, Roberto Mart\u00ednez, varios concejales de la corporaci\u00f3n, entre ellos la tambi\u00e9n diputada Virginia Almanza, y por el presidente de \u2018Villa de Aldeamayor\u2019, \u00c1lvaro Sanz Ferrero.<\/p>\n<p>Tras la introducci\u00f3n del vicepresidente, ha tomado la palabra el alcalde para destacar el orgullo que para el municipio supone tener una asociaci\u00f3n como \u2018Villa de Aldeamayor\u201d que \u201cse encarga a\u00f1o tras a\u00f1o de brindarnos excelentes muestras de todo tipo y \u00faltimamente, ya llevamos unos cuantos a\u00f1os, siete en concreto, las ediciones a la luz de la Virgen del Compasco en las que se superan a\u00f1o a a\u00f1o invitando a gente de lo mejor que hay en el panorama nacional a nivel musical\u201d.<\/p>\n<p>Despu\u00e9s de invitar a vecinos y visitantes a disfrutar de esta experiencia, Mart\u00ednez ha dado la palabra \u00c1lvaro Sanz Ferrero quien ha explicado que \u201cla idea surgi\u00f3 en aras de diversificar las actividades culturales que se hacen en la localidad. Tenemos un amplio surtido de conciertos de m\u00fasica folcl\u00f3rica y de otros estilos y pensamos que ten\u00eda cabida realizar conciertos de m\u00fasica cl\u00e1sica para que hubiese un espectro de vecinos que pudieran acceder a este tipo de m\u00fasica. El hecho de hacerlo en homenaje a la Virgen de Compasco fue por la devoci\u00f3n y la tradici\u00f3n, ya secular, que en este pueblo hay en torno a nuestra patrona y que se sustancia en diferentes eventos a lo largo del a\u00f1o, como por ejemplo la primera de las dos romer\u00edas que hay en su honor, la del 13 de mayo.<\/p>\n<p>La cita de este 2026 ser\u00e1 a partir de las 21:00 horas en la iglesia parroquial y los protagonistas, la Camerata Europa y el tenor David Galicia Ruiz.<\/p>\n<p>El Cuarteto Camerata Europa est\u00e1 formada por profesores de la Orquesta Sinf\u00f3nica de Castilla y Le\u00f3n, procedentes de varios pa\u00edses de Europa y Am\u00e9rica del Norte. Surgi\u00f3 con el deseo de disfrutar de un repertorio musical que, si bien es muy conocido por el p\u00fablico en general, no es muy frecuentemente interpretado. En este sentido, los vecinos que acudan a este concierto podr\u00e1n disfrutar de obras de Mozart, Vivaldi, Verdi, Chopin o Tchaikovski en la esfera cl\u00e1sica o de otras fuera de \u00e9sta como es el Bohemian Rapsody de la banda brit\u00e1nica Queen.<\/p>\n<p>La diferente procedencia de sus componentes, su variada formaci\u00f3n y la aportaci\u00f3n del tenor David Galicia, que los acompa\u00f1ar\u00e1 en algunas de sus piezas musicales, como el <em>Nessun Dorma<\/em> de Puccini o el <em>Va pensiero<\/em> de Verdi, hacen que se convierta en un concierto \u00fanico.<\/p>\n<p>David Galicia Ruiz, tenor y agricultor, naci\u00f3 en Fuente el Sol (Valladolid) y entr\u00f3 a formar parte del coro Catedralicio de Valladolid como solista de Voces Blancas desde los 11 hasta los 24 a\u00f1os. Posteriormente, entrado en la madurez, canta como solista en el Coro Proyecto Opera y en los coros Universitarios, Escuela Municipal de M\u00fasica y Capilla Cl\u00e1sica adem\u00e1s de ser miembro de otros coros como el Voces Amigas de Medina del Campo.<\/p>\n<p>\u201cEl repertorio elegido para la ocasi\u00f3n, la ac\u00fastica de la Iglesia de San Mart\u00edn de Tours y la tenue iluminaci\u00f3n con velas del recinto, dotar\u00e1n de una magia especial a esta cita a la que esperamos que acuda el mayor n\u00famero de personas\u201d se\u00f1ala el propio Sanz Ferrero.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-756119da e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"756119da\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-975fa41 elementor-widget elementor-widget-image\" data-id=\"975fa41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.granjapinilla.com\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"639\" height=\"150\" src=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-granja-pinilla.jpg\" class=\"attachment-large size-large wp-image-105\" alt=\"\" srcset=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-granja-pinilla.jpg 639w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-granja-pinilla-300x70.jpg 300w\" sizes=\"(max-width: 639px) 100vw, 639px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Cultura y tradici\u00f3n M\u00fasica a la luz de la Virgen de Compasco para comenzar con el programa del Privilegio de Villazgo de Aldeamayor S\u00e9ptima edici\u00f3n del concierto de m\u00fasica cl\u00e1sica promovido por la Asociaci\u00f3n Villa de Aldeamayor organizado conjuntamente con el Ayuntamiento Se celebrar\u00e1 el martes, 12 de mayo, a las 21:00 horas en la iglesia parroquial con la partici\u00f3n de la Camerata Europa y el tenor David Galicia Ruiz Pueblosycomarcas.com;&nbsp;@PueblosComarcas El pr\u00f3ximo martes, 12 de mayo, Aldeamayor de San Mart\u00edn dar\u00e1 el pistoletazo de salida al programa de actividades de su Privilegio de Villazgo 2026, celebraci\u00f3n con la que la localidad recuerda la obtenci\u00f3n de su independencia respecto a Portillo el 19 de mayo de 1776. Lo har\u00e1 con una cita que a\u00fana m\u00fasica, tradici\u00f3n y devoci\u00f3n como es la s\u00e9ptima edici\u00f3n de \u2018M\u00fasica a la luz de la Virgen de Compasco\u2019 que el Ayuntamiento de la localidad coorganiza con la Asociaci\u00f3n Cultural Villa de Aldamayor, promotora de la iniciativa, y con la inestimable colaboraci\u00f3n de la Cofrad\u00eda de Nuestra Se\u00f1ora de Compasco y de la Parroquia de San Mart\u00edn de Tours. Este concierto ha sido presentado en la ma\u00f1ana de hoy por el vicepresidente de la Diputaci\u00f3n de Valladolid, V\u00edctor Alonso, que ha estado acompa\u00f1ado por el alcalde de Aldeamayor, Roberto Mart\u00ednez, varios concejales de la corporaci\u00f3n, entre ellos la tambi\u00e9n diputada Virginia Almanza, y por el presidente de \u2018Villa de Aldeamayor\u2019, \u00c1lvaro Sanz Ferrero. Tras la introducci\u00f3n del vicepresidente, ha tomado la palabra el alcalde para destacar el orgullo que para el municipio supone tener una asociaci\u00f3n como \u2018Villa de Aldeamayor\u201d que \u201cse encarga a\u00f1o tras a\u00f1o de brindarnos excelentes muestras de todo tipo y \u00faltimamente, ya llevamos unos cuantos a\u00f1os, siete en concreto, las ediciones a la luz de la Virgen del Compasco en las que se superan a\u00f1o a a\u00f1o invitando a gente de lo mejor que hay en el panorama nacional a nivel musical\u201d. Despu\u00e9s de invitar a vecinos y visitantes a disfrutar de esta experiencia, Mart\u00ednez ha dado la palabra \u00c1lvaro Sanz Ferrero quien ha explicado que \u201cla idea surgi\u00f3 en aras de diversificar las actividades culturales que se hacen en la localidad. Tenemos un amplio surtido de conciertos de m\u00fasica folcl\u00f3rica y de otros estilos y pensamos que ten\u00eda cabida realizar conciertos de m\u00fasica cl\u00e1sica para que hubiese un espectro de vecinos que pudieran acceder a este tipo de m\u00fasica. El hecho de hacerlo en homenaje a la Virgen de Compasco fue por la devoci\u00f3n y la tradici\u00f3n, ya secular, que en este pueblo hay en torno a nuestra patrona y que se sustancia en diferentes eventos a lo largo del a\u00f1o, como por ejemplo la primera de las dos romer\u00edas que hay en su honor, la del 13 de mayo. La cita de este 2026 ser\u00e1 a partir de las 21:00 horas en la iglesia parroquial y los protagonistas, la Camerata Europa y el tenor David Galicia Ruiz. El Cuarteto Camerata Europa est\u00e1 formada por profesores de la Orquesta Sinf\u00f3nica de Castilla y Le\u00f3n, procedentes de varios pa\u00edses de Europa y Am\u00e9rica del Norte. Surgi\u00f3 con el deseo de disfrutar de un repertorio musical que, si bien es muy conocido por el p\u00fablico en general, no es muy frecuentemente interpretado. En este sentido, los vecinos que acudan a este concierto podr\u00e1n disfrutar de obras de Mozart, Vivaldi, Verdi, Chopin o Tchaikovski en la esfera cl\u00e1sica o de otras fuera de \u00e9sta como es el Bohemian Rapsody de la banda brit\u00e1nica Queen. La diferente procedencia de sus componentes, su variada formaci\u00f3n y la aportaci\u00f3n del tenor David Galicia, que los acompa\u00f1ar\u00e1 en algunas de sus piezas musicales, como el Nessun Dorma de Puccini o el Va pensiero de Verdi, hacen que se convierta en un concierto \u00fanico. David Galicia Ruiz, tenor y agricultor, naci\u00f3 en Fuente el Sol (Valladolid) y entr\u00f3 a formar parte del coro Catedralicio de Valladolid como solista de Voces Blancas desde los 11 hasta los 24 a\u00f1os. Posteriormente, entrado en la madurez, canta como solista en el Coro Proyecto Opera y en los coros Universitarios, Escuela Municipal de M\u00fasica y Capilla Cl\u00e1sica adem\u00e1s de ser miembro de otros coros como el Voces Amigas de Medina del Campo. \u201cEl repertorio elegido para la ocasi\u00f3n, la ac\u00fastica de la Iglesia de San Mart\u00edn de Tours y la tenue iluminaci\u00f3n con velas del recinto, dotar\u00e1n de una magia especial a esta cita a la que esperamos que acuda el mayor n\u00famero de personas\u201d se\u00f1ala el propio Sanz Ferrero.<\/p>","protected":false},"author":2,"featured_media":11333,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ngg_post_thumbnail":0,"footnotes":""},"categories":[14,18,16],"tags":[35,26,558,60],"class_list":["post-11332","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-y-tradicion","category-ocio","category-portada","tag-aldeamayor-de-san-martin","tag-diputacion-de-valladolid","tag-villa-de-aldeamayor","tag-virgen-de-compasco"],"aioseo_notices":[],"rttpg_featured_image_url":{"full":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_musica_luz_viegen_compasco_aldeamayor.jpeg",800,400,false],"landscape":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_musica_luz_viegen_compasco_aldeamayor.jpeg",800,400,false],"portraits":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_musica_luz_viegen_compasco_aldeamayor.jpeg",800,400,false],"thumbnail":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_musica_luz_viegen_compasco_aldeamayor-150x150.jpeg",150,150,true],"medium":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_musica_luz_viegen_compasco_aldeamayor-300x150.jpeg",300,150,true],"large":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_musica_luz_viegen_compasco_aldeamayor.jpeg",800,400,false],"1536x1536":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_musica_luz_viegen_compasco_aldeamayor.jpeg",800,400,false],"2048x2048":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_musica_luz_viegen_compasco_aldeamayor.jpeg",800,400,false],"trp-custom-language-flag":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_musica_luz_viegen_compasco_aldeamayor-18x9.jpeg",18,9,true]},"rttpg_author":{"display_name":"Juanjo","author_link":"https:\/\/pueblosycomarcas.com\/en\/author\/pueblosycomarcas\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/pueblosycomarcas.com\/en\/category\/cultura-y-tradicion\/\" rel=\"category tag\">Cultura y Tradici\u00f3n<\/a> <a href=\"https:\/\/pueblosycomarcas.com\/en\/category\/ocio\/\" rel=\"category tag\">Ocio<\/a> <a href=\"https:\/\/pueblosycomarcas.com\/en\/category\/portada\/\" rel=\"category tag\">Portada<\/a>","rttpg_excerpt":"Cultura y tradici\u00f3n M\u00fasica a la luz de la Virgen de Compasco para comenzar con el programa del Privilegio de Villazgo de Aldeamayor S\u00e9ptima edici\u00f3n del concierto de m\u00fasica cl\u00e1sica promovido por la Asociaci\u00f3n Villa de Aldeamayor organizado conjuntamente con el Ayuntamiento Se celebrar\u00e1 el martes, 12 de mayo, a las 21:00 horas en la&hellip;","_links":{"self":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts\/11332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/comments?post=11332"}],"version-history":[{"count":5,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts\/11332\/revisions"}],"predecessor-version":[{"id":11338,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts\/11332\/revisions\/11338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/media\/11333"}],"wp:attachment":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/media?parent=11332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/categories?post=11332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/tags?post=11332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}