{"id":11297,"date":"2026-05-06T12:00:00","date_gmt":"2026-05-06T11:00:00","guid":{"rendered":"https:\/\/pueblosycomarcas.com\/?p=11297"},"modified":"2026-05-06T14:16:39","modified_gmt":"2026-05-06T13:16:39","slug":"el-actor-vallisoletano-jesus-puebla-galardonado-en-los-xxi-premios-moretti-de-teatro","status":"publish","type":"post","link":"https:\/\/pueblosycomarcas.com\/en\/el-actor-vallisoletano-jesus-puebla-galardonado-en-los-xxi-premios-moretti-de-teatro\/","title":{"rendered":"El actor vallisoletano Jes\u00fas Puebla, galardonado en los XXI Premios Moretti de Teatro"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"11297\" class=\"elementor elementor-11297\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d3da891 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"d3da891\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-34f9f73f e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"34f9f73f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e4e5c2 elementor-widget elementor-widget-image\" data-id=\"e4e5c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.termicasalfonso.es\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"220\" src=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-instalaciones-alfonso.jpg\" class=\"attachment-large size-large wp-image-107\" alt=\"\" srcset=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-instalaciones-alfonso.jpg 400w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-instalaciones-alfonso-300x165.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-161ee2d5 elementor-widget elementor-widget-text-editor\" data-id=\"161ee2d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><h6><strong><em>Cultura y tradici\u00f3n<\/em><\/strong><\/h6><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d9113e3 elementor-widget elementor-widget-heading\" data-id=\"7d9113e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">El actor vallisoletano Jes\u00fas Puebla, galardonado en los XXI Premios Moretti de Teatro<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56dec49f elementor-widget elementor-widget-text-editor\" data-id=\"56dec49f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><h6><em><strong>Recibir\u00e1 el Premio \u201cCu\u00e9ntame un Cuento\u201d el pr\u00f3ximo 31 de mayo en Pedrajas de San Esteban<\/strong><\/em><\/h6><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30a8450e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"30a8450e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10402e40 elementor-widget elementor-widget-image\" data-id=\"10402e40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_jesus_puebla.jpg\" class=\"attachment-large size-large wp-image-11298\" alt=\"\" srcset=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_jesus_puebla.jpg 800w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_jesus_puebla-300x150.jpg 300w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_jesus_puebla-768x384.jpg 768w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_jesus_puebla-18x9.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54f1bdc8 elementor-widget elementor-widget-text-editor\" data-id=\"54f1bdc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.facebook.com\/Pueblos-y-Comarcas-125437870924169\/?fref=ts\"><strong><em>Pueblosycomarcas.com<\/em><\/strong><\/a><strong><em>;\u00a0<\/em><\/strong><a href=\"https:\/\/twitter.com\/PueblosComarcas\"><strong><em>@PueblosComarcas<\/em><\/strong><\/a><\/p><p>El actor y mimo vallisoletano <strong>Jes\u00fas Puebla<\/strong> ser\u00e1 uno de los protagonistas destacados de la XXI edici\u00f3n de los Premios Moretti de Teatro, al ser reconocido con el <strong>Premio \u201cCu\u00e9ntame un Cuento\u201d<\/strong>, un galard\u00f3n que pone en valor su amplia y s\u00f3lida trayectoria dentro del \u00e1mbito esc\u00e9nico.<\/p><p>Este reconocimiento, concedido por la Asociaci\u00f3n Cultural Zarandaja, distingue la aportaci\u00f3n de Puebla al teatro gestual y a la pantomima enfocado a un p\u00fablico familiar, disciplinas en las que se ha consolidado como una figura de referencia tras cerca de cuatro d\u00e9cadas de carrera. Su trabajo, caracterizado por la expresividad y la conexi\u00f3n directa con el p\u00fablico, ha dejado huella tanto en los escenarios de Valladolid como en otros circuitos teatrales.<\/p><p>Jes\u00fas Puebla ha desarrollado un lenguaje propio dentro de las artes esc\u00e9nicas, participando en numerosos montajes y contribuyendo a la difusi\u00f3n del teatro como herramienta cultural y social.<\/p><p>Los Premios Moretti, creados en 2004, rinden homenaje a la figura del actor y director uruguayo Juan Carlos Moretti y reconocen cada a\u00f1o a profesionales y colectivos destacados del panorama teatral.<\/p><p>La ceremonia de entrega de premios tendr\u00e1 lugar el pr\u00f3ximo <strong>domingo 31 de mayo<\/strong> en el <strong>Centro de Cultura \u2018Eloy Arribas\u2019 de Pedrajas de San Esteban (Valladolid)<\/strong>, en el marco de los Encuentros Moretti de Teatro.<\/p><p>Este galard\u00f3n supone un nuevo reconocimiento a la trayectoria de Jes\u00fas Puebla y a su compromiso con las artes esc\u00e9nicas, consolidando su papel como uno de los nombres relevantes del teatro vallisoletano.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-435bec64 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"435bec64\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e2d54cf elementor-widget elementor-widget-image\" data-id=\"e2d54cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.granjapinilla.com\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"639\" height=\"150\" src=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-granja-pinilla.jpg\" class=\"attachment-large size-large wp-image-105\" alt=\"\" srcset=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-granja-pinilla.jpg 639w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-granja-pinilla-300x70.jpg 300w\" sizes=\"(max-width: 639px) 100vw, 639px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Cultura y tradici\u00f3n El actor vallisoletano Jes\u00fas Puebla, galardonado en los XXI Premios Moretti de Teatro Recibir\u00e1 el Premio \u201cCu\u00e9ntame un Cuento\u201d el pr\u00f3ximo 31 de mayo en Pedrajas de San Esteban Pueblosycomarcas.com;\u00a0@PueblosComarcas El actor y mimo vallisoletano Jes\u00fas Puebla ser\u00e1 uno de los protagonistas destacados de la XXI edici\u00f3n de los Premios Moretti de Teatro, al ser reconocido con el Premio \u201cCu\u00e9ntame un Cuento\u201d, un galard\u00f3n que pone en valor su amplia y s\u00f3lida trayectoria dentro del \u00e1mbito esc\u00e9nico. Este reconocimiento, concedido por la Asociaci\u00f3n Cultural Zarandaja, distingue la aportaci\u00f3n de Puebla al teatro gestual y a la pantomima enfocado a un p\u00fablico familiar, disciplinas en las que se ha consolidado como una figura de referencia tras cerca de cuatro d\u00e9cadas de carrera. Su trabajo, caracterizado por la expresividad y la conexi\u00f3n directa con el p\u00fablico, ha dejado huella tanto en los escenarios de Valladolid como en otros circuitos teatrales. Jes\u00fas Puebla ha desarrollado un lenguaje propio dentro de las artes esc\u00e9nicas, participando en numerosos montajes y contribuyendo a la difusi\u00f3n del teatro como herramienta cultural y social. Los Premios Moretti, creados en 2004, rinden homenaje a la figura del actor y director uruguayo Juan Carlos Moretti y reconocen cada a\u00f1o a profesionales y colectivos destacados del panorama teatral. La ceremonia de entrega de premios tendr\u00e1 lugar el pr\u00f3ximo domingo 31 de mayo en el Centro de Cultura \u2018Eloy Arribas\u2019 de Pedrajas de San Esteban (Valladolid), en el marco de los Encuentros Moretti de Teatro. Este galard\u00f3n supone un nuevo reconocimiento a la trayectoria de Jes\u00fas Puebla y a su compromiso con las artes esc\u00e9nicas, consolidando su papel como uno de los nombres relevantes del teatro vallisoletano.<\/p>","protected":false},"author":2,"featured_media":11298,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ngg_post_thumbnail":0,"footnotes":""},"categories":[14,16],"tags":[556,42,557],"class_list":["post-11297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-y-tradicion","category-portada","tag-jesus-puebla","tag-pedrajas-de-san-esteban","tag-premios-moretti"],"aioseo_notices":[],"rttpg_featured_image_url":{"full":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_jesus_puebla.jpg",800,400,false],"landscape":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_jesus_puebla.jpg",800,400,false],"portraits":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_jesus_puebla.jpg",800,400,false],"thumbnail":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_jesus_puebla-150x150.jpg",150,150,true],"medium":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_jesus_puebla-300x150.jpg",300,150,true],"large":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_jesus_puebla.jpg",800,400,false],"1536x1536":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_jesus_puebla.jpg",800,400,false],"2048x2048":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_jesus_puebla.jpg",800,400,false],"trp-custom-language-flag":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260506_jesus_puebla-18x9.jpg",18,9,true]},"rttpg_author":{"display_name":"Juanjo","author_link":"https:\/\/pueblosycomarcas.com\/en\/author\/pueblosycomarcas\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/pueblosycomarcas.com\/en\/category\/cultura-y-tradicion\/\" rel=\"category tag\">Cultura y Tradici\u00f3n<\/a> <a href=\"https:\/\/pueblosycomarcas.com\/en\/category\/portada\/\" rel=\"category tag\">Portada<\/a>","rttpg_excerpt":"Cultura y tradici\u00f3n El actor vallisoletano Jes\u00fas Puebla, galardonado en los XXI Premios Moretti de Teatro Recibir\u00e1 el Premio \u201cCu\u00e9ntame un Cuento\u201d el pr\u00f3ximo 31 de mayo en Pedrajas de San Esteban Pueblosycomarcas.com;\u00a0@PueblosComarcas El actor y mimo vallisoletano Jes\u00fas Puebla ser\u00e1 uno de los protagonistas destacados de la XXI edici\u00f3n de los Premios Moretti de&hellip;","_links":{"self":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts\/11297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/comments?post=11297"}],"version-history":[{"count":5,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts\/11297\/revisions"}],"predecessor-version":[{"id":11303,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts\/11297\/revisions\/11303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/media\/11298"}],"wp:attachment":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/media?parent=11297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/categories?post=11297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/tags?post=11297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}