{"id":11269,"date":"2026-05-05T17:07:52","date_gmt":"2026-05-05T16:07:52","guid":{"rendered":"https:\/\/pueblosycomarcas.com\/?p=11269"},"modified":"2026-05-05T17:10:18","modified_gmt":"2026-05-05T16:10:18","slug":"nace-una-nueva-asociacion-en-pedrajas-de-san-esteban-en-respuesta-a-la-instalacion-de-la-planta-de-biogas","status":"publish","type":"post","link":"https:\/\/pueblosycomarcas.com\/en\/nace-una-nueva-asociacion-en-pedrajas-de-san-esteban-en-respuesta-a-la-instalacion-de-la-planta-de-biogas\/","title":{"rendered":"Nace una nueva asociaci\u00f3n en Pedrajas de San Esteban en respuesta a la instalaci\u00f3n de la planta de biog\u00e1s"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"11269\" class=\"elementor elementor-11269\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79467abf e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"79467abf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-577ab772 elementor-widget elementor-widget-image\" data-id=\"577ab772\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.termicasalfonso.es\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"220\" src=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-instalaciones-alfonso.jpg\" class=\"attachment-large size-large wp-image-107\" alt=\"\" srcset=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-instalaciones-alfonso.jpg 400w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-instalaciones-alfonso-300x165.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a239a6a elementor-widget elementor-widget-text-editor\" data-id=\"3a239a6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><h6><strong><em>Tierra de Pinares<\/em><\/strong><\/h6><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28b3341a elementor-widget elementor-widget-heading\" data-id=\"28b3341a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nace una nueva asociaci\u00f3n en Pedrajas de San Esteban en respuesta a la instalaci\u00f3n de la planta de biog\u00e1s<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71f92aaf elementor-widget elementor-widget-text-editor\" data-id=\"71f92aaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><h6><em><strong>En apenas 7 d\u00edas desde la constituci\u00f3n de esta nueva asociaci\u00f3n vecinal, ya se han inscrito m\u00e1s de doscientas personas, lo que para sus impulsores demuestra \u201cel malestar existente en el municipio por la posible instalaci\u00f3n de la planta de biog\u00e1s en Pedrajas\u201d. <\/strong><\/em><\/h6><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c286f78 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5c286f78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c7c225b elementor-widget elementor-widget-image\" data-id=\"3c7c225b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260505_pedrajas.jpeg\" class=\"attachment-large size-large wp-image-11270\" alt=\"\" srcset=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260505_pedrajas.jpeg 800w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260505_pedrajas-300x150.jpeg 300w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260505_pedrajas-768x384.jpeg 768w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260505_pedrajas-18x9.jpeg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c04549d elementor-widget elementor-widget-text-editor\" data-id=\"5c04549d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.facebook.com\/Pueblos-y-Comarcas-125437870924169\/?fref=ts\"><strong><em>Pueblosycomarcas.com<\/em><\/strong><\/a><strong><em>;\u00a0<\/em><\/strong><a href=\"https:\/\/twitter.com\/PueblosComarcas\"><strong><em>@PueblosComarcas<\/em><\/strong><\/a><\/p><p>Una nueva asociaci\u00f3n, \u201cPedrajas Viva\u201d ha surgido como respuesta a la posible instalaci\u00f3n de una planta de biog\u00e1s en el entorno de la localidad.<\/p><p>En apenas 7 d\u00edas desde la constituci\u00f3n de esta nueva asociaci\u00f3n vecinal, ya se <strong>han inscrito m\u00e1s de doscientas personas<\/strong>, lo que demuestra \u201c<strong><em>el malestar existente en el municipio por la posible instalaci\u00f3n de la planta de biog\u00e1s en Pedrajas<\/em><\/strong>\u201d.<\/p><p>La creaci\u00f3n de esta asociaci\u00f3n nace, seg\u00fan explican sus impulsores, \u201c<strong><em>de la preocupaci\u00f3n vecinal ante la posible implantaci\u00f3n de esta instalaci\u00f3n y su impacto en el entorno rura<\/em><\/strong><em>l\u201d.<\/em> El colectivo afirma que su objetivo es canalizar la oposici\u00f3n social, ofrecer informaci\u00f3n a la poblaci\u00f3n y defender los intereses del municipio frente a lo que consideran un proyecto que no tiene cabida en Pedrajas.<\/p><p>El proyecto que presenta la empresa BIOFERTILIZANTES CH4 se sit\u00faa a 2,5 kil\u00f3metros del municipio en lo alto del monte de Pedrajas y prev\u00e9 procesar 140.000 toneladas de residuos de purines, lo que generara un tr\u00e1fico diario de m\u00e1s de 45 camiones por el municipio.<\/p><p>Este colectivo seg\u00fan se\u00f1alan desde la asociaci\u00f3n \u201c<strong><em>tiene como objetivos la protecci\u00f3n del entorno natural de Pedrajas, la defensa de la salud publica el medio ambiente y la calidad de vida de los vecinos y vecinas de Pedrajas y la vigilancia y seguimiento de proyectos industriales, energ\u00e9ticos o infraestructuras de posible impacto negativo para el municipio<\/em><\/strong>\u201d.\u00a0 \u00a0<\/p><p>En un primer comunicado de la asociaci\u00f3n \u201cPedrajas Viva\u201d que ha hecho llegar a la ciudadan\u00eda, rechazan radicalmente el proyecto por los gases y olores que genera, por la posible contaminaci\u00f3n de acu\u00edferos, la degradaci\u00f3n del entorno y por la p\u00e9rdida de valor patrimonial.<\/p><p>Con la asociaci\u00f3n ya en marcha han iniciado una serie de contactos con autoridades, y diferentes asociaciones y colectivos para sumar fuerzas. Adem\u00e1s, la asociaci\u00f3n ha adelantado que ya trabaja en la planificaci\u00f3n de diferentes actos reivindicativos, que empezar\u00e1n con la recogida de firmas, la colocaci\u00f3n de pancartas, y una gran concentraci\u00f3n, con el objetivo de dar visibilidad a su rechazo.<\/p><p>Durante la primera asamblea, los asistentes expresaron su preocupaci\u00f3n sobre diversos aspectos, enfatizando especialmente la cuesti\u00f3n de por qu\u00e9 la planta se ubicar\u00eda en Pedrajas y la ausencia de un estudio a mayor escala que respaldara el cumplimiento del principio de proximidad. Los vecinos consideran que \u00ab<strong><em>existen ubicaciones m\u00e1s apropiadas para la planta, especialmente aquellas m\u00e1s cercanas a la fuente de producci\u00f3n de los residuos\u201d<\/em><\/strong><\/p><p>\u00a0\u00abPedrajas Viva\u00bb ha invitado a los vecinos del municipio y de la comarca a que se sumen al colectivo para\u00a0<strong>\u00abdefender su pueblo y su vida\u00bb<\/strong>.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1fe56f55 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"1fe56f55\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21ad9603 elementor-widget elementor-widget-image\" data-id=\"21ad9603\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.granjapinilla.com\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"639\" height=\"150\" src=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-granja-pinilla.jpg\" class=\"attachment-large size-large wp-image-105\" alt=\"\" srcset=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-granja-pinilla.jpg 639w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-granja-pinilla-300x70.jpg 300w\" sizes=\"(max-width: 639px) 100vw, 639px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Tierra de Pinares Nace una nueva asociaci\u00f3n en Pedrajas de San Esteban en respuesta a la instalaci\u00f3n de la planta de biog\u00e1s En apenas 7 d\u00edas desde la constituci\u00f3n de esta nueva asociaci\u00f3n vecinal, ya se han inscrito m\u00e1s de doscientas personas, lo que para sus impulsores demuestra \u201cel malestar existente en el municipio por la posible instalaci\u00f3n de la planta de biog\u00e1s en Pedrajas\u201d. Pueblosycomarcas.com;\u00a0@PueblosComarcas Una nueva asociaci\u00f3n, \u201cPedrajas Viva\u201d ha surgido como respuesta a la posible instalaci\u00f3n de una planta de biog\u00e1s en el entorno de la localidad. En apenas 7 d\u00edas desde la constituci\u00f3n de esta nueva asociaci\u00f3n vecinal, ya se han inscrito m\u00e1s de doscientas personas, lo que demuestra \u201cel malestar existente en el municipio por la posible instalaci\u00f3n de la planta de biog\u00e1s en Pedrajas\u201d. La creaci\u00f3n de esta asociaci\u00f3n nace, seg\u00fan explican sus impulsores, \u201cde la preocupaci\u00f3n vecinal ante la posible implantaci\u00f3n de esta instalaci\u00f3n y su impacto en el entorno rural\u201d. El colectivo afirma que su objetivo es canalizar la oposici\u00f3n social, ofrecer informaci\u00f3n a la poblaci\u00f3n y defender los intereses del municipio frente a lo que consideran un proyecto que no tiene cabida en Pedrajas. El proyecto que presenta la empresa BIOFERTILIZANTES CH4 se sit\u00faa a 2,5 kil\u00f3metros del municipio en lo alto del monte de Pedrajas y prev\u00e9 procesar 140.000 toneladas de residuos de purines, lo que generara un tr\u00e1fico diario de m\u00e1s de 45 camiones por el municipio. Este colectivo seg\u00fan se\u00f1alan desde la asociaci\u00f3n \u201ctiene como objetivos la protecci\u00f3n del entorno natural de Pedrajas, la defensa de la salud publica el medio ambiente y la calidad de vida de los vecinos y vecinas de Pedrajas y la vigilancia y seguimiento de proyectos industriales, energ\u00e9ticos o infraestructuras de posible impacto negativo para el municipio\u201d.\u00a0 \u00a0 En un primer comunicado de la asociaci\u00f3n \u201cPedrajas Viva\u201d que ha hecho llegar a la ciudadan\u00eda, rechazan radicalmente el proyecto por los gases y olores que genera, por la posible contaminaci\u00f3n de acu\u00edferos, la degradaci\u00f3n del entorno y por la p\u00e9rdida de valor patrimonial. Con la asociaci\u00f3n ya en marcha han iniciado una serie de contactos con autoridades, y diferentes asociaciones y colectivos para sumar fuerzas. Adem\u00e1s, la asociaci\u00f3n ha adelantado que ya trabaja en la planificaci\u00f3n de diferentes actos reivindicativos, que empezar\u00e1n con la recogida de firmas, la colocaci\u00f3n de pancartas, y una gran concentraci\u00f3n, con el objetivo de dar visibilidad a su rechazo. Durante la primera asamblea, los asistentes expresaron su preocupaci\u00f3n sobre diversos aspectos, enfatizando especialmente la cuesti\u00f3n de por qu\u00e9 la planta se ubicar\u00eda en Pedrajas y la ausencia de un estudio a mayor escala que respaldara el cumplimiento del principio de proximidad. Los vecinos consideran que \u00abexisten ubicaciones m\u00e1s apropiadas para la planta, especialmente aquellas m\u00e1s cercanas a la fuente de producci\u00f3n de los residuos\u201d \u00a0\u00abPedrajas Viva\u00bb ha invitado a los vecinos del municipio y de la comarca a que se sumen al colectivo para\u00a0\u00abdefender su pueblo y su vida\u00bb.\u00a0<\/p>","protected":false},"author":2,"featured_media":11270,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ngg_post_thumbnail":0,"footnotes":""},"categories":[16,5],"tags":[42,555],"class_list":["post-11269","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portada","category-actualidad","tag-pedrajas-de-san-esteban","tag-pedrajas-viva"],"aioseo_notices":[],"rttpg_featured_image_url":{"full":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260505_pedrajas.jpeg",800,400,false],"landscape":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260505_pedrajas.jpeg",800,400,false],"portraits":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260505_pedrajas.jpeg",800,400,false],"thumbnail":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260505_pedrajas-150x150.jpeg",150,150,true],"medium":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260505_pedrajas-300x150.jpeg",300,150,true],"large":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260505_pedrajas.jpeg",800,400,false],"1536x1536":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260505_pedrajas.jpeg",800,400,false],"2048x2048":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260505_pedrajas.jpeg",800,400,false],"trp-custom-language-flag":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260505_pedrajas-18x9.jpeg",18,9,true]},"rttpg_author":{"display_name":"Juanjo","author_link":"https:\/\/pueblosycomarcas.com\/en\/author\/pueblosycomarcas\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/pueblosycomarcas.com\/en\/category\/portada\/\" rel=\"category tag\">Portada<\/a> <a href=\"https:\/\/pueblosycomarcas.com\/en\/category\/actualidad\/\" rel=\"category tag\">Tierra de Pinares<\/a>","rttpg_excerpt":"Tierra de Pinares Nace una nueva asociaci\u00f3n en Pedrajas de San Esteban en respuesta a la instalaci\u00f3n de la planta de biog\u00e1s En apenas 7 d\u00edas desde la constituci\u00f3n de esta nueva asociaci\u00f3n vecinal, ya se han inscrito m\u00e1s de doscientas personas, lo que para sus impulsores demuestra \u201cel malestar existente en el municipio por&hellip;","_links":{"self":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts\/11269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/comments?post=11269"}],"version-history":[{"count":5,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts\/11269\/revisions"}],"predecessor-version":[{"id":11275,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts\/11269\/revisions\/11275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/media\/11270"}],"wp:attachment":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/media?parent=11269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/categories?post=11269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/tags?post=11269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}