{"id":11215,"date":"2026-05-06T05:01:00","date_gmt":"2026-05-06T04:01:00","guid":{"rendered":"https:\/\/pueblosycomarcas.com\/?p=11215"},"modified":"2026-05-05T11:42:33","modified_gmt":"2026-05-05T10:42:33","slug":"concluyen-las-obras-en-la-potabilizadora-de-laguna-de-duero-tras-cerca-de-dos-anos-de-trabajos-de-mejora","status":"publish","type":"post","link":"https:\/\/pueblosycomarcas.com\/en\/concluyen-las-obras-en-la-potabilizadora-de-laguna-de-duero-tras-cerca-de-dos-anos-de-trabajos-de-mejora\/","title":{"rendered":"Concluyen las obras en la Potabilizadora de Laguna de Duero tras cerca de dos a\u00f1os de trabajos de mejora"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"11215\" class=\"elementor elementor-11215\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b51eb5e e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"6b51eb5e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e1ae6e8 elementor-widget elementor-widget-image\" data-id=\"6e1ae6e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.termicasalfonso.es\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"220\" src=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-instalaciones-alfonso.jpg\" class=\"attachment-large size-large wp-image-107\" alt=\"\" srcset=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-instalaciones-alfonso.jpg 400w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-instalaciones-alfonso-300x165.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f22ccb9 elementor-widget elementor-widget-text-editor\" data-id=\"3f22ccb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><h6><strong><em>OTHER REGIONS<\/em><\/strong><\/h6><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3942f303 elementor-widget elementor-widget-heading\" data-id=\"3942f303\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Concluyen las obras en la Potabilizadora de Laguna de Duero tras cerca de dos a\u00f1os de trabajos de mejora<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13a9b2d4 elementor-widget elementor-widget-text-editor\" data-id=\"13a9b2d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><h6><em><strong>Con esta intervenci\u00f3n se pasa a tener una planta completamente digitalizada, que mide las 24 horas del d\u00eda los par\u00e1metros del agua, avisa a los encargados si se registran anomal\u00edas al momento, y se termina con los episodios de turbidez y problemas derivados de una mala potabilizaci\u00f3n<\/strong><\/em><\/h6><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f977f38 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1f977f38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cd0584e elementor-widget elementor-widget-image\" data-id=\"2cd0584e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260504_potabilizadora_laguna-1.jpg\" class=\"attachment-large size-large wp-image-11216\" alt=\"\" srcset=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260504_potabilizadora_laguna-1.jpg 800w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260504_potabilizadora_laguna-1-300x150.jpg 300w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260504_potabilizadora_laguna-1-768x384.jpg 768w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260504_potabilizadora_laguna-1-18x9.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27b0b507 elementor-widget elementor-widget-text-editor\" data-id=\"27b0b507\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.facebook.com\/Pueblos-y-Comarcas-125437870924169\/?fref=ts\"><strong><em>Pueblosycomarcas.com<\/em><\/strong><\/a><strong><em>;\u00a0<\/em><\/strong><a href=\"https:\/\/twitter.com\/PueblosComarcas\"><strong><em>@PueblosComarcas<\/em><\/strong><\/a><\/p><p>Han sido 23 meses de trabajos en una intervenci\u00f3n compleja para adecuar la Planta Potabilizadora de Laguna de Duero al siglo XXI. Esas intervenciones llegan ahora a su fin, tras la conclusi\u00f3n de la segunda etapa de sus obras.<\/p><p>Con una inversi\u00f3n total cercana a los 400.000 euros, de los cuales 130.000 han salido de las arcas municipales y el resto han llegado de subvenciones por parte de la Junta de Castilla y Le\u00f3n, la planta resultante est\u00e1 completamente digitalizada, mide las 24 horas del d\u00eda los par\u00e1metros del agua y avisa a los encargados en todo momento de si alguno no est\u00e1 dentro de los l\u00edmites marcados.<\/p><p>Para llegar a este punto, primero se comenz\u00f3 la obra de emergencia en mayo de 2024 en la que es conocida como la ETAP 2. Hubo que intervenir de esta manera para dar fin a los graves episodios de turbidez en el agua que sufr\u00edan los vecinos y que hac\u00edan que las mediciones del agua estuviesen al l\u00edmite de lo considerado potable.\u00a0 All\u00ed se llevaron a cabo mejoras muy necesarias en la zona de filtraci\u00f3n y en el control de dosificaci\u00f3n de reactivos, realizando el cambio de arena y uniendo las decantaciones de las plantas I y II para un aporte mayor de caudal a la zona de filtrado, adem\u00e1s de toda su automatizaci\u00f3n.<\/p><p>Durante la ejecuci\u00f3n de esta intervenci\u00f3n, se estuvo distribuyendo agua \u00fanicamente desde la ETAP 1. Su coste fue cubierto por fondos propios del consistorio y ascendi\u00f3 a 130.000 euros. Tras esta intervenci\u00f3n, y tal y como se planific\u00f3 tras los estudios que dieron como resultado las obras, se comenz\u00f3 la intervenci\u00f3n en la segunda parte. Aqu\u00ed se ha acometido una intervenci\u00f3n muy similar a la primera que incluye la rehabilitaci\u00f3n de sistemas de filtraci\u00f3n, la modernizaci\u00f3n de v\u00e1lvulas posicionadoras, la digitalizaci\u00f3n del sistema de explotaci\u00f3n y el control y digitalizaci\u00f3n de par\u00e1metros de proceso.<\/p><p>Estos trabajos se han podido realizar gracias a una subvenci\u00f3n de la Junta de Castilla y Le\u00f3n de 150.000 euros. Adem\u00e1s, se han instalado placas solares en el exterior y en la parte superior del edificio, consiguiendo un ahorro a los vecinos del 30 % en energ\u00eda. En este caso, la instalaci\u00f3n se ha llevado a cabo por una subvenci\u00f3n de algo m\u00e1s de 72.000 euros procedente, igualmente, del gobierno auton\u00f3mico.<\/p><p>Gracias a estas obras, la Potabilizadora actual est\u00e1 preparada para abastecer agua a 35.000 vecinos. Durante la presentaci\u00f3n de la misma a los miembros de la Corporaci\u00f3n Municipal realizada el pasado lunes, el alcalde del municipio, Avelino \u00c1lvarez, ha declarado estar \u201cmuy satisfecho porque el problema del ciclo del agua era lo que m\u00e1s preocupaba a los vecinos y con esta soluci\u00f3n cumplimos, adem\u00e1s de nuestro compromiso con los vecinos, una de nuestra principal promesa electoral\u201d \u201cCon toda la digitalizaci\u00f3n y las nuevas mediciones, garantizamos que el agua que se ofrece es de total calidad\u201d. Por su parte, Alfredo Fadrique, concejal de Servicios Urbanos ha explicado que ahora las dos plantas quedan conectadas, cosa que antes no suced\u00eda, se detecta la anal\u00edtica del agua cuando lo cogemos del canal, detectamos problemas que pueda tener de origen, y tenemos anal\u00edticas constantes que nos ayudan a tener un control total en la red del agua. Si a d\u00eda de hoy se dan episodios de turbidez son por aver\u00edas o roturas en tuber\u00edas en la red, pero ya no por problemas en el proceso de depurado\u201d.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-24c53020 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"24c53020\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-232a9ba8 elementor-widget elementor-widget-image\" data-id=\"232a9ba8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.granjapinilla.com\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"639\" height=\"150\" src=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-granja-pinilla.jpg\" class=\"attachment-large size-large wp-image-105\" alt=\"\" srcset=\"https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-granja-pinilla.jpg 639w, https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2025\/07\/banner-granja-pinilla-300x70.jpg 300w\" sizes=\"(max-width: 639px) 100vw, 639px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Otras comarcas Concluyen las obras en la Potabilizadora de Laguna de Duero tras cerca de dos a\u00f1os de trabajos de mejora Con esta intervenci\u00f3n se pasa a tener una planta completamente digitalizada, que mide las 24 horas del d\u00eda los par\u00e1metros del agua, avisa a los encargados si se registran anomal\u00edas al momento, y se termina con los episodios de turbidez y problemas derivados de una mala potabilizaci\u00f3n Pueblosycomarcas.com;\u00a0@PueblosComarcas Han sido 23 meses de trabajos en una intervenci\u00f3n compleja para adecuar la Planta Potabilizadora de Laguna de Duero al siglo XXI. Esas intervenciones llegan ahora a su fin, tras la conclusi\u00f3n de la segunda etapa de sus obras. Con una inversi\u00f3n total cercana a los 400.000 euros, de los cuales 130.000 han salido de las arcas municipales y el resto han llegado de subvenciones por parte de la Junta de Castilla y Le\u00f3n, la planta resultante est\u00e1 completamente digitalizada, mide las 24 horas del d\u00eda los par\u00e1metros del agua y avisa a los encargados en todo momento de si alguno no est\u00e1 dentro de los l\u00edmites marcados. Para llegar a este punto, primero se comenz\u00f3 la obra de emergencia en mayo de 2024 en la que es conocida como la ETAP 2. Hubo que intervenir de esta manera para dar fin a los graves episodios de turbidez en el agua que sufr\u00edan los vecinos y que hac\u00edan que las mediciones del agua estuviesen al l\u00edmite de lo considerado potable.\u00a0 All\u00ed se llevaron a cabo mejoras muy necesarias en la zona de filtraci\u00f3n y en el control de dosificaci\u00f3n de reactivos, realizando el cambio de arena y uniendo las decantaciones de las plantas I y II para un aporte mayor de caudal a la zona de filtrado, adem\u00e1s de toda su automatizaci\u00f3n. Durante la ejecuci\u00f3n de esta intervenci\u00f3n, se estuvo distribuyendo agua \u00fanicamente desde la ETAP 1. Su coste fue cubierto por fondos propios del consistorio y ascendi\u00f3 a 130.000 euros. Tras esta intervenci\u00f3n, y tal y como se planific\u00f3 tras los estudios que dieron como resultado las obras, se comenz\u00f3 la intervenci\u00f3n en la segunda parte. Aqu\u00ed se ha acometido una intervenci\u00f3n muy similar a la primera que incluye la rehabilitaci\u00f3n de sistemas de filtraci\u00f3n, la modernizaci\u00f3n de v\u00e1lvulas posicionadoras, la digitalizaci\u00f3n del sistema de explotaci\u00f3n y el control y digitalizaci\u00f3n de par\u00e1metros de proceso. Estos trabajos se han podido realizar gracias a una subvenci\u00f3n de la Junta de Castilla y Le\u00f3n de 150.000 euros. Adem\u00e1s, se han instalado placas solares en el exterior y en la parte superior del edificio, consiguiendo un ahorro a los vecinos del 30 % en energ\u00eda. En este caso, la instalaci\u00f3n se ha llevado a cabo por una subvenci\u00f3n de algo m\u00e1s de 72.000 euros procedente, igualmente, del gobierno auton\u00f3mico. Gracias a estas obras, la Potabilizadora actual est\u00e1 preparada para abastecer agua a 35.000 vecinos. Durante la presentaci\u00f3n de la misma a los miembros de la Corporaci\u00f3n Municipal realizada el pasado lunes, el alcalde del municipio, Avelino \u00c1lvarez, ha declarado estar \u201cmuy satisfecho porque el problema del ciclo del agua era lo que m\u00e1s preocupaba a los vecinos y con esta soluci\u00f3n cumplimos, adem\u00e1s de nuestro compromiso con los vecinos, una de nuestra principal promesa electoral\u201d \u201cCon toda la digitalizaci\u00f3n y las nuevas mediciones, garantizamos que el agua que se ofrece es de total calidad\u201d. Por su parte, Alfredo Fadrique, concejal de Servicios Urbanos ha explicado que ahora las dos plantas quedan conectadas, cosa que antes no suced\u00eda, se detecta la anal\u00edtica del agua cuando lo cogemos del canal, detectamos problemas que pueda tener de origen, y tenemos anal\u00edticas constantes que nos ayudan a tener un control total en la red del agua. Si a d\u00eda de hoy se dan episodios de turbidez son por aver\u00edas o roturas en tuber\u00edas en la red, pero ya no por problemas en el proceso de depurado\u201d.<\/p>","protected":false},"author":2,"featured_media":11216,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ngg_post_thumbnail":0,"footnotes":""},"categories":[10,16],"tags":[58,55,57],"class_list":["post-11215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-otras-comarcas","category-portada","tag-ayuntamiento-de-laguna-de-duero","tag-junta-de-castilla-y-leon","tag-laguna-de-duero"],"aioseo_notices":[],"rttpg_featured_image_url":{"full":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260504_potabilizadora_laguna-1.jpg",800,400,false],"landscape":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260504_potabilizadora_laguna-1.jpg",800,400,false],"portraits":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260504_potabilizadora_laguna-1.jpg",800,400,false],"thumbnail":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260504_potabilizadora_laguna-1-150x150.jpg",150,150,true],"medium":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260504_potabilizadora_laguna-1-300x150.jpg",300,150,true],"large":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260504_potabilizadora_laguna-1.jpg",800,400,false],"1536x1536":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260504_potabilizadora_laguna-1.jpg",800,400,false],"2048x2048":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260504_potabilizadora_laguna-1.jpg",800,400,false],"trp-custom-language-flag":["https:\/\/pueblosycomarcas.com\/wp-content\/uploads\/2026\/05\/20260504_potabilizadora_laguna-1-18x9.jpg",18,9,true]},"rttpg_author":{"display_name":"Juanjo","author_link":"https:\/\/pueblosycomarcas.com\/en\/author\/pueblosycomarcas\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/pueblosycomarcas.com\/en\/category\/otras-comarcas\/\" rel=\"category tag\">Otras Comarcas<\/a> <a href=\"https:\/\/pueblosycomarcas.com\/en\/category\/portada\/\" rel=\"category tag\">Portada<\/a>","rttpg_excerpt":"Otras comarcas Concluyen las obras en la Potabilizadora de Laguna de Duero tras cerca de dos a\u00f1os de trabajos de mejora Con esta intervenci\u00f3n se pasa a tener una planta completamente digitalizada, que mide las 24 horas del d\u00eda los par\u00e1metros del agua, avisa a los encargados si se registran anomal\u00edas al momento, y se&hellip;","_links":{"self":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts\/11215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/comments?post=11215"}],"version-history":[{"count":5,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts\/11215\/revisions"}],"predecessor-version":[{"id":11221,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/posts\/11215\/revisions\/11221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/media\/11216"}],"wp:attachment":[{"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/media?parent=11215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/categories?post=11215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pueblosycomarcas.com\/en\/wp-json\/wp\/v2\/tags?post=11215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}